{"id":921,"date":"2007-07-03T18:33:34","date_gmt":"2007-07-03T18:33:34","guid":{"rendered":"https:\/\/cinema.video\/imma-turbau"},"modified":"2026-04-10T03:17:38","modified_gmt":"2026-04-10T01:17:38","slug":"imma-turbau","status":"publish","type":"post","link":"https:\/\/cinema.video\/it\/imma-turbau","title":{"rendered":"Imma Turbau"},"content":{"rendered":"<p><P><STRONG>Sandra e David, i protagonisti del tuo libro, sono due adolescenti. E&#8217; ai loro coetanei che volevi rivolgerti scrivendo la loro storia?<\/STRONG> &#8220;Sinceramente no, non ho pensato questo libro per i giovani, anche perch\u00e9 non credevo che fosse conveniente per loro. <BR>Poi invece l&#8217;hanno letto ed \u00e8 piaciuto molto, come succede sempre da adolescenti quando si scopre qualcosa che sarebbe meglio non fare. Comunque, in Spagna il libro l&#8217;hanno letto di pi\u00f9 gli adulti.&#8221; <\/P><br \/>\n<P><STRONG>In Italia sei stata definita &#8220;l&#8217;anti-Moccia&#8221;, che ne pensi? Conosci quest&#8217;autore? <BR><\/STRONG>&#8220;Mi hanno parlato di lui, ma non lo conosco. <BR>Posso dire che io non faccio una letteratura sentimentale, e non volevo che questa storia rappresentasse un&#8217;educazione sentimentale classica, ce ne sono gi\u00e0\u00a0 tante scritte superbamente. <BR>La generazione a cui appartengono David e Sandra \u00e8 molto diversa da quella di oggi, per esempio nel modo di comunicare: negli anni 80 non esistevano gli sms e nessuno aveva il computer. <BR>Ma \u00e8 sicuramente diversa anche da quella &#8220;romantico-hippy&#8221; degli anni 60.&#8221; <IMG alt=\"\" hspace=5 src=\"https:\/\/cinema.video\/wp-content\/uploads\/IMMA.jpg\" align=right vspace=2 border=0><\/P><br \/>\n<P><STRONG>Hai giudicato postivamente la decisone di trasformare il tuo libro in film?<\/STRONG> <BR>&#8220;S\u00ec: il mio libro \u00e8 gi\u00e0\u00a0 scritto, ha avuto fortuna e vive di vita propria, non si pu\u00f2 fare pi\u00f9 niente per cambiarlo. <BR>Ho detto, scherzando, al regista: se il film sar\u00e0\u00a0 brutto, sar\u00e0\u00a0 brutto solo per te, se invece sar\u00e0\u00a0 bello, lo sar\u00e0\u00a0 per entrambi!&#8221; <\/P><br \/>\n<P><STRONG>Hai collaborato alla stesura della sceneggiatura?<\/STRONG> <BR>&#8220;Ho lavorato molto con il regista e lo sceneggiatore, Salvador Garcia Ruiz, che si era gi\u00e0\u00a0 cimentato con successo nell&#8217;adattamento di altri romanzi (tra cui &#8220;Le Voci della Notte&#8221; di Natalia Ginzburg). <BR>E&#8217; stata un&#8217; esperienza &#8220;bestiale&#8221;, inizialemente ero molto coinvolta, poi per\u00f2 ho preferito allontanarmi, e non perch\u00e9 si fossero create tensioni, tutt&#8217;altro. <BR>Ho capito che la presenza dell&#8217;autore del romanzo poteva costituire un problema: chiedevano la mia approvazione continuamente, anche sul minimo dettaglio (per esempio l&#8217;et\u00e0\u00a0 di un personaggio)&#8221;\u00a6ma alla fine il romanzo e il film sono due cose diverse.&#8221; <\/P><br \/>\n<P><STRONG>Il tuo libro contiene delle immagini che sembra gi\u00e0\u00a0 di vedere sullo schermo. Penso, ad esempio, a quando Sandra , rompendo la penna stilografica, e vedendo le macchie nere d&#8217;inchiostro disegnare &#8221; laghi e fiumi&#8221; sul lucido foglio bianco, scopre la sua passione per la grafica. Credi che la ricchezza d&#8217;immagini sia d&#8217;aiuto per il regista?<\/STRONG> <BR>&#8220;Da una parte s\u00ec, ma bisogna stare attenti a non farsi trarre in inganno. Quando \u00e8 iniziato il lavoro della sceneggiatura, ad esempio, \u00e8 venuto fuori che tutto nel libro \u00e8 filtrato attraverso gli occhi di Sandra, anche il personaggio di David, e questo al cinema non va. <BR>Lo sceneggiatore ha dovuto lavorare molto per costruire, in parallelo anche la sua storia, fatta di situazioni e momenti che fossero indipendenti dallo sguardo di lei.&#8221; <\/P><br \/>\n<P><STRONG>Soddisfatta del risultato finale? <BR><\/STRONG>&#8220;Avevo un po&#8217; di paura prima di leggere l&#8217;ultima versione, ma devo dire che hanno fatto un lavoro stupendo, in cui credo molto. <BR>E nonostante i cambiamenti, c&#8217;\u00e8 dentro tutto quello che volevo dire. Quello che mi piace \u00e8 che la storia sia buona: non \u00e8 necessario leggere il libro per capire il film e viceversa.&#8221; <\/P><br \/>\n<P>&nbsp;<\/P><br \/>\n<P>Cinema&amp;Video International&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; n.6-7 Giugno\/Luglio 2007<\/P><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NULL<\/p>\n","protected":false},"author":101032,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAow3e7fCw:productID":"","_crdt_document":"","footnotes":""},"categories":[1],"tags":[82],"class_list":{"0":"post-921","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-senza-categoria","7":"tag-libro-e-schermo"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Imma Turbau - Cinema &amp; Video International<\/title>\n<meta name=\"description\" content=\"Imma Turbau \u2013 imma turbau. Sandra e David, i protagonisti del tuo libro, sono due adolescenti. E&#039; ai loro coetanei che volevi rivolgerti scrivendo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cinema.video\/it\/imma-turbau\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Imma Turbau\" \/>\n<meta property=\"og:description\" content=\"Imma Turbau \u2013 imma turbau. Sandra e David, i protagonisti del tuo libro, sono due adolescenti. E&#039; ai loro coetanei che volevi rivolgerti scrivendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cinema.video\/it\/imma-turbau\" \/>\n<meta property=\"og:site_name\" content=\"Cinema &amp; Video International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CinemaVideoInternational\/\" \/>\n<meta property=\"article:published_time\" content=\"2007-07-03T18:33:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T01:17:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cinema.video\/wp-content\/uploads\/2026\/04\/CinemVideo_LogoBlack.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1336\" \/>\n\t<meta property=\"og:image:height\" content=\"224\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Davide Morena\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davide Morena\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cinema.video\\\/it\\\/imma-turbau#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cinema.video\\\/it\\\/imma-turbau\"},\"author\":{\"name\":\"Davide Morena\",\"@id\":\"https:\\\/\\\/cinema.video\\\/it#\\\/schema\\\/person\\\/b63ca05986911bf3a53c6c027c27b8b7\"},\"headline\":\"Imma Turbau\",\"datePublished\":\"2007-07-03T18:33:34+00:00\",\"dateModified\":\"2026-04-10T01:17:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cinema.video\\\/it\\\/imma-turbau\"},\"wordCount\":546,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cinema.video\\\/it#organization\"},\"keywords\":[\"Libro e schermo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cinema.video\\\/it\\\/imma-turbau#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cinema.video\\\/it\\\/imma-turbau\",\"url\":\"https:\\\/\\\/cinema.video\\\/it\\\/imma-turbau\",\"name\":\"Imma Turbau - Cinema &amp; Video International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cinema.video\\\/it#website\"},\"datePublished\":\"2007-07-03T18:33:34+00:00\",\"dateModified\":\"2026-04-10T01:17:38+00:00\",\"description\":\"Imma Turbau \u2013 imma turbau. Sandra e David, i protagonisti del tuo libro, sono due adolescenti. E' ai loro coetanei che volevi rivolgerti scrivendo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cinema.video\\\/it\\\/imma-turbau#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cinema.video\\\/it\\\/imma-turbau\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cinema.video\\\/it\\\/imma-turbau#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cinema.video\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Imma Turbau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cinema.video\\\/it#website\",\"url\":\"https:\\\/\\\/cinema.video\\\/it\",\"name\":\"Cinema & Video International\",\"description\":\"Film &amp; Audiovisual Industry Trade Magazine\",\"publisher\":{\"@id\":\"https:\\\/\\\/cinema.video\\\/it#organization\"},\"alternateName\":\"Cinema & Video\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cinema.video\\\/it?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cinema.video\\\/it#organization\",\"name\":\"Cinema & Video\",\"url\":\"https:\\\/\\\/cinema.video\\\/it\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cinema.video\\\/it#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cinema.video\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/CinemVideo_LogoBlack.png\",\"contentUrl\":\"https:\\\/\\\/cinema.video\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/CinemVideo_LogoBlack.png\",\"width\":1336,\"height\":224,\"caption\":\"Cinema & Video\"},\"image\":{\"@id\":\"https:\\\/\\\/cinema.video\\\/it#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CinemaVideoInternational\\\/\",\"https:\\\/\\\/www.instagram.com\\\/cinemaevideointernational\\\/\",\"https:\\\/\\\/it.linkedin.com\\\/company\\\/cinema-video-international\"],\"description\":\"Media Consulting & Marketing Agency\",\"email\":\"hello@darostudio.com\",\"legalName\":\"DARO studio LLC\",\"foundingDate\":\"2021-02-16\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cinema.video\\\/it#\\\/schema\\\/person\\\/b63ca05986911bf3a53c6c027c27b8b7\",\"name\":\"Davide Morena\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4304209e0c1a7f0eafbc1fa01b5157cb233998514f3a0ff9ea99ae43a0f44009?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4304209e0c1a7f0eafbc1fa01b5157cb233998514f3a0ff9ea99ae43a0f44009?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4304209e0c1a7f0eafbc1fa01b5157cb233998514f3a0ff9ea99ae43a0f44009?s=96&d=mm&r=g\",\"caption\":\"Davide Morena\"},\"url\":\"https:\\\/\\\/cinema.video\\\/it\\\/author\\\/davide-morena\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Imma Turbau - Cinema &amp; Video International","description":"Imma Turbau \u2013 imma turbau. Sandra e David, i protagonisti del tuo libro, sono due adolescenti. E' ai loro coetanei che volevi rivolgerti scrivendo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cinema.video\/it\/imma-turbau","og_locale":"it_IT","og_type":"article","og_title":"Imma Turbau","og_description":"Imma Turbau \u2013 imma turbau. Sandra e David, i protagonisti del tuo libro, sono due adolescenti. E' ai loro coetanei che volevi rivolgerti scrivendo","og_url":"https:\/\/cinema.video\/it\/imma-turbau","og_site_name":"Cinema &amp; Video International","article_publisher":"https:\/\/www.facebook.com\/CinemaVideoInternational\/","article_published_time":"2007-07-03T18:33:34+00:00","article_modified_time":"2026-04-10T01:17:38+00:00","og_image":[{"width":1336,"height":224,"url":"https:\/\/cinema.video\/wp-content\/uploads\/2026\/04\/CinemVideo_LogoBlack.png","type":"image\/png"}],"author":"Davide Morena","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Davide Morena","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cinema.video\/it\/imma-turbau#article","isPartOf":{"@id":"https:\/\/cinema.video\/it\/imma-turbau"},"author":{"name":"Davide Morena","@id":"https:\/\/cinema.video\/it#\/schema\/person\/b63ca05986911bf3a53c6c027c27b8b7"},"headline":"Imma Turbau","datePublished":"2007-07-03T18:33:34+00:00","dateModified":"2026-04-10T01:17:38+00:00","mainEntityOfPage":{"@id":"https:\/\/cinema.video\/it\/imma-turbau"},"wordCount":546,"commentCount":0,"publisher":{"@id":"https:\/\/cinema.video\/it#organization"},"keywords":["Libro e schermo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cinema.video\/it\/imma-turbau#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cinema.video\/it\/imma-turbau","url":"https:\/\/cinema.video\/it\/imma-turbau","name":"Imma Turbau - Cinema &amp; Video International","isPartOf":{"@id":"https:\/\/cinema.video\/it#website"},"datePublished":"2007-07-03T18:33:34+00:00","dateModified":"2026-04-10T01:17:38+00:00","description":"Imma Turbau \u2013 imma turbau. Sandra e David, i protagonisti del tuo libro, sono due adolescenti. E' ai loro coetanei che volevi rivolgerti scrivendo","breadcrumb":{"@id":"https:\/\/cinema.video\/it\/imma-turbau#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cinema.video\/it\/imma-turbau"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cinema.video\/it\/imma-turbau#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cinema.video\/it"},{"@type":"ListItem","position":2,"name":"Imma Turbau"}]},{"@type":"WebSite","@id":"https:\/\/cinema.video\/it#website","url":"https:\/\/cinema.video\/it","name":"Cinema & Video International","description":"Film &amp; Audiovisual Industry Trade Magazine","publisher":{"@id":"https:\/\/cinema.video\/it#organization"},"alternateName":"Cinema & Video","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cinema.video\/it?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cinema.video\/it#organization","name":"Cinema & Video","url":"https:\/\/cinema.video\/it","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cinema.video\/it#\/schema\/logo\/image\/","url":"https:\/\/cinema.video\/wp-content\/uploads\/2026\/04\/CinemVideo_LogoBlack.png","contentUrl":"https:\/\/cinema.video\/wp-content\/uploads\/2026\/04\/CinemVideo_LogoBlack.png","width":1336,"height":224,"caption":"Cinema & Video"},"image":{"@id":"https:\/\/cinema.video\/it#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CinemaVideoInternational\/","https:\/\/www.instagram.com\/cinemaevideointernational\/","https:\/\/it.linkedin.com\/company\/cinema-video-international"],"description":"Media Consulting & Marketing Agency","email":"hello@darostudio.com","legalName":"DARO studio LLC","foundingDate":"2021-02-16","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/cinema.video\/it#\/schema\/person\/b63ca05986911bf3a53c6c027c27b8b7","name":"Davide Morena","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4304209e0c1a7f0eafbc1fa01b5157cb233998514f3a0ff9ea99ae43a0f44009?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4304209e0c1a7f0eafbc1fa01b5157cb233998514f3a0ff9ea99ae43a0f44009?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4304209e0c1a7f0eafbc1fa01b5157cb233998514f3a0ff9ea99ae43a0f44009?s=96&d=mm&r=g","caption":"Davide Morena"},"url":"https:\/\/cinema.video\/it\/author\/davide-morena"}]}},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/ph672m-eR","_links":{"self":[{"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/posts\/921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/users\/101032"}],"replies":[{"embeddable":true,"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/comments?post=921"}],"version-history":[{"count":1,"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/posts\/921\/revisions"}],"predecessor-version":[{"id":304303,"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/posts\/921\/revisions\/304303"}],"wp:attachment":[{"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/media?parent=921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/categories?post=921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/tags?post=921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}