{"id":44138,"date":"2020-09-15T16:01:16","date_gmt":"2020-09-15T16:01:16","guid":{"rendered":"https:\/\/cinema.video\/?p=44138"},"modified":"2026-04-10T03:50:02","modified_gmt":"2026-04-10T01:50:02","slug":"visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre","status":"publish","type":"post","link":"https:\/\/cinema.video\/it\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre","title":{"rendered":"VISIONI DAL MONDO Visioni Incontra Online dal 17 al 19 settembre"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cinema.video\/wp-content\/uploads\/visioni-3-1024x576.jpg\" alt=\"\" class=\"wp-image-44139\" width=\"323\" height=\"181\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">12 progetti documentari work in progress in concorso e un programma di panel e tavole rotonde che vedr\u00e0 confrontarsi i professionisti del settore sulle nuove tendenze, le politiche e le opportunit\u00e0 di questo particolare momento storico: questi i principali ingredienti della sesta edizione di <strong>Visioni Incontra<\/strong>,<strong>\u00a0<\/strong>la sezione<em> Industry <\/em>del Festival Internazionale del Documentario Visioni dal Mondo, che si terr\u00e0 da gioved\u00ec 17 a sabato 19 settembre. La sezione che nelle cinque edizioni ha visto la partecipazione di oltre 700 professionisti del settore accreditati prevede il\u00a0<strong>Concorso<\/strong>\u00a0dedicato ai progetti documentari italiani ancora nella fase work in progress con la presentazione di 12 titoli che concorrono al <strong>Premio Visioni Incontra<\/strong> del valore di 2.500 euro (tramite pitch a cui seguiranno incontri one to one) .\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cIl&nbsp;cinema non si \u00e8 fermato, il cinema non si ferma &#8211;&nbsp;afferma&nbsp;<strong>Cinzia Mas\u00f2tina<\/strong>, head of Industry -.Questa \u00e8 una constatazione di cui Visioni Incontra \u00e8 e sar\u00e0 testimonianza diretta. Il documentario, lo storytelling, il pedinamento della realt\u00e0 e la sua rappresentazione, sono semmai usciti rafforzati da questa esperienza che ha nuovamente e drammaticamente saldato la \u201cStoria\u201d con \u201cle storie\u201d di ciascuno di noi, l\u2019esperienza individuale con quella comunitaria, il microcosmo con il Mondo.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo stato dell&#8217;arte e dell&#8217;industria documentaria sar\u00e0 indagato dai seguenti incontri:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>la&nbsp;<strong>round table<\/strong>&nbsp;\u201c<em>La serialit\u00e0 nel documentario. Generi e linee editoriali: la parola ai broadcaster<\/em>\u201d che vuole analizzare la crescente rilevanza che va assumendo la serialit\u00e0 nel genere documentario e insieme fare una ricognizione sulle nuove linee editoriali dei broadcaster, reti e OTT, in programma gioved\u00ec 17 settembre alle ore 18.00. Parteciperanno Cristiano Girola Senior Programming &amp; OTT Content Manager Discovery Italia, Roberto Pisoni Direttore Sky Arte, Enrico Bufalini Direttore Archivio, Produzione, Distribuzione, Post Produzione, Affari Generali &amp; HR Istituto Luce Cinecitt\u00e0, Karina Laterza Vice Direttore Rai Doc Produzione Documentari.&nbsp;Coordina Cinzia Mas\u00f2tina<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>il&nbsp;<strong>panel<\/strong>&nbsp;<em>\u201cRAI DOCUMENTARI: linee editoriali e strategie\u201d<\/em>&nbsp;&#8211; Relatore Duilio Gianmaria, Direzione produzione documentari Rai, in programma venerd\u00ec 18 settembre alle ore 11.00. Introduce Cinzia Mas\u00f2tina<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>il<strong>&nbsp;panel<\/strong><em>&nbsp;<\/em><em>\u201cEuropa Creativa 2021-2027, a che punto siamo? Prospettive per il nuovo Programma MEDIA e aggiornamento sulle politiche europee, in particolare le opportunit\u00e0 offerte dal recovery fund per il settore audiovisivo italiano\u201d-<\/em>&nbsp;Relatrice Silvia Sandrone, Creative Europe Desk Italy \u2013 Media,&nbsp;in programma venerd\u00ec 18 settembre alle ore 12.00.Introduce Cinzia Mas\u00f2tina<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>la&nbsp;<strong>round table&nbsp;<\/strong>\u201c<em>Sala e streaming: coesistenza o scelta? Il cinema documentario tra nuove opportunit\u00e0 e possibili \u201criserve indiane<\/em>\u201d\u201d per approfondire le modalit\u00e0 di fruizione mediante device e piattaforme che, anche a causa della recente emergenza sanitaria, hanno incrementato l\u2019offerta del cosiddetto \u201ccinema difficile\u201d e cinema del reale, in calendario venerd\u00ec 18 settembre ore 14.30. Parteciperanno Domenico Dinoia Presidente della FICE (Federazione Italiana Cinema d\u2019Essai) AGIS-ANEC Lombardia, Lorenzo Ardicini Presidente Cg Entertainment, Maurizio Imbriale Responsabile Produzione e gestione dell\u2019offerta RaiPlay e Digital, Pinangelo Marino Vice Presidente Doc\/it-Associazione Documentaristi italiani, Ciro Scala Head of Content Acquisition CHILI TV, Andrea Fabiano Vice Presidente Multimedia TIM, Dino Vannini Editorial &amp; Communications Manager Sky, Stefania Ippoliti Responsabile Mediateca e Area Cinema Fondazione Sistema Toscana, Francesco Giraldo Segretario generale ACEC-Associazione Esercenti Cattolici, Gianluca Guzzo Founder CEO MyMovies.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si svolger\u00e0 dal 17 al 19 settembre la sesta edizione di Visioni Incontra, la sezione industry del Festival Internazionale Visioni dal Mondo<\/p>\n","protected":false},"author":26,"featured_media":44139,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAow3e7fCw:productID":"","_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[189],"tags":[2322,2334],"class_list":["post-44138","post","type-post","status-publish","format-standard","has-post-thumbnail","category-events","tag-documentary","tag-events"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>VISIONI DAL MONDO Visioni Incontra Online dal 17 al 19 settembre - Cinema &amp; Video International<\/title>\n<meta name=\"description\" content=\"VISIONI DAL MONDO Visioni Incontra Online dal 17 al 19 settembre \u2013 visioni dal mondo visioni incontra online. 12 progetti documentari work in progress\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cinema.video\/it\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VISIONI DAL MONDO Visioni Incontra Online dal 17 al 19 settembre\" \/>\n<meta property=\"og:description\" content=\"VISIONI DAL MONDO Visioni Incontra Online dal 17 al 19 settembre \u2013 visioni dal mondo visioni incontra online. 12 progetti documentari work in progress\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cinema.video\/it\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre\" \/>\n<meta property=\"og:site_name\" content=\"Cinema &amp; Video International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CinemaVideoInternational\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-15T16:01:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T01:50:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cinema.video\/wp-content\/uploads\/visioni-3-e1602488248279.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editorial\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editorial\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cinema.video\\\/it\\\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cinema.video\\\/it\\\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre\"},\"author\":{\"name\":\"Editorial\",\"@id\":\"https:\\\/\\\/cinema.video\\\/it#\\\/schema\\\/person\\\/aeb01b91d874e8b01e76a1db04c668c6\"},\"headline\":\"VISIONI DAL MONDO Visioni Incontra Online dal 17 al 19 settembre\",\"datePublished\":\"2020-09-15T16:01:16+00:00\",\"dateModified\":\"2026-04-10T01:50:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cinema.video\\\/it\\\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre\"},\"wordCount\":534,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cinema.video\\\/it#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cinema.video\\\/it\\\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cinema.video\\\/wp-content\\\/uploads\\\/visioni-3-e1602488248279.jpg\",\"keywords\":[\"DOCUMENTARY\",\"EVENTS\"],\"articleSection\":[\"EVENTS\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cinema.video\\\/it\\\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cinema.video\\\/it\\\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre\",\"url\":\"https:\\\/\\\/cinema.video\\\/it\\\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre\",\"name\":\"VISIONI DAL MONDO Visioni Incontra Online dal 17 al 19 settembre - Cinema &amp; Video International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cinema.video\\\/it#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cinema.video\\\/it\\\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cinema.video\\\/it\\\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cinema.video\\\/wp-content\\\/uploads\\\/visioni-3-e1602488248279.jpg\",\"datePublished\":\"2020-09-15T16:01:16+00:00\",\"dateModified\":\"2026-04-10T01:50:02+00:00\",\"description\":\"VISIONI DAL MONDO Visioni Incontra Online dal 17 al 19 settembre \u2013 visioni dal mondo visioni incontra online. 12 progetti documentari work in progress\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cinema.video\\\/it\\\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cinema.video\\\/it\\\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cinema.video\\\/it\\\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre#primaryimage\",\"url\":\"https:\\\/\\\/cinema.video\\\/wp-content\\\/uploads\\\/visioni-3-e1602488248279.jpg\",\"contentUrl\":\"https:\\\/\\\/cinema.video\\\/wp-content\\\/uploads\\\/visioni-3-e1602488248279.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cinema.video\\\/it\\\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cinema.video\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VISIONI DAL MONDO Visioni Incontra Online dal 17 al 19 settembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cinema.video\\\/it#website\",\"url\":\"https:\\\/\\\/cinema.video\\\/it\",\"name\":\"Cinema & Video International\",\"description\":\"Film &amp; Audiovisual B2B Industry Trade Platform Magazine\",\"publisher\":{\"@id\":\"https:\\\/\\\/cinema.video\\\/it#organization\"},\"alternateName\":\"Cinema & Video\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cinema.video\\\/it?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cinema.video\\\/it#organization\",\"name\":\"Cinema & Video\",\"url\":\"https:\\\/\\\/cinema.video\\\/it\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cinema.video\\\/it#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cinema.video\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/CinemVideo_LogoBlack.png\",\"contentUrl\":\"https:\\\/\\\/cinema.video\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/CinemVideo_LogoBlack.png\",\"width\":1336,\"height\":224,\"caption\":\"Cinema & Video\"},\"image\":{\"@id\":\"https:\\\/\\\/cinema.video\\\/it#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CinemaVideoInternational\\\/\",\"https:\\\/\\\/www.instagram.com\\\/cinemaevideointernational\\\/\",\"https:\\\/\\\/it.linkedin.com\\\/company\\\/cinema-video-international\"],\"description\":\"Media Consulting & Marketing Agency\",\"email\":\"hello@darostudio.com\",\"legalName\":\"DARO studio LLC\",\"foundingDate\":\"2021-02-16\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"publishingPrinciples\":\"https:\\\/\\\/cinema.video\\\/about\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cinema.video\\\/it#\\\/schema\\\/person\\\/aeb01b91d874e8b01e76a1db04c668c6\",\"name\":\"Editorial\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06ad6f92eb14745b75fb592cadf8139d33242d81c9c8b085133c450aaf0b9731?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06ad6f92eb14745b75fb592cadf8139d33242d81c9c8b085133c450aaf0b9731?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06ad6f92eb14745b75fb592cadf8139d33242d81c9c8b085133c450aaf0b9731?s=96&d=mm&r=g\",\"caption\":\"Editorial\"},\"url\":\"https:\\\/\\\/cinema.video\\\/it\\\/author\\\/redazione\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"VISIONI DAL MONDO Visioni Incontra Online dal 17 al 19 settembre - Cinema &amp; Video International","description":"VISIONI DAL MONDO Visioni Incontra Online dal 17 al 19 settembre \u2013 visioni dal mondo visioni incontra online. 12 progetti documentari work in progress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cinema.video\/it\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre","og_locale":"it_IT","og_type":"article","og_title":"VISIONI DAL MONDO Visioni Incontra Online dal 17 al 19 settembre","og_description":"VISIONI DAL MONDO Visioni Incontra Online dal 17 al 19 settembre \u2013 visioni dal mondo visioni incontra online. 12 progetti documentari work in progress","og_url":"https:\/\/cinema.video\/it\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre","og_site_name":"Cinema &amp; Video International","article_publisher":"https:\/\/www.facebook.com\/CinemaVideoInternational\/","article_published_time":"2020-09-15T16:01:16+00:00","article_modified_time":"2026-04-10T01:50:02+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/cinema.video\/wp-content\/uploads\/visioni-3-e1602488248279.jpg","type":"image\/jpeg"}],"author":"Editorial","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Editorial","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cinema.video\/it\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre#article","isPartOf":{"@id":"https:\/\/cinema.video\/it\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre"},"author":{"name":"Editorial","@id":"https:\/\/cinema.video\/it#\/schema\/person\/aeb01b91d874e8b01e76a1db04c668c6"},"headline":"VISIONI DAL MONDO Visioni Incontra Online dal 17 al 19 settembre","datePublished":"2020-09-15T16:01:16+00:00","dateModified":"2026-04-10T01:50:02+00:00","mainEntityOfPage":{"@id":"https:\/\/cinema.video\/it\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre"},"wordCount":534,"commentCount":0,"publisher":{"@id":"https:\/\/cinema.video\/it#organization"},"image":{"@id":"https:\/\/cinema.video\/it\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre#primaryimage"},"thumbnailUrl":"https:\/\/cinema.video\/wp-content\/uploads\/visioni-3-e1602488248279.jpg","keywords":["DOCUMENTARY","EVENTS"],"articleSection":["EVENTS"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cinema.video\/it\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cinema.video\/it\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre","url":"https:\/\/cinema.video\/it\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre","name":"VISIONI DAL MONDO Visioni Incontra Online dal 17 al 19 settembre - Cinema &amp; Video International","isPartOf":{"@id":"https:\/\/cinema.video\/it#website"},"primaryImageOfPage":{"@id":"https:\/\/cinema.video\/it\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre#primaryimage"},"image":{"@id":"https:\/\/cinema.video\/it\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre#primaryimage"},"thumbnailUrl":"https:\/\/cinema.video\/wp-content\/uploads\/visioni-3-e1602488248279.jpg","datePublished":"2020-09-15T16:01:16+00:00","dateModified":"2026-04-10T01:50:02+00:00","description":"VISIONI DAL MONDO Visioni Incontra Online dal 17 al 19 settembre \u2013 visioni dal mondo visioni incontra online. 12 progetti documentari work in progress","breadcrumb":{"@id":"https:\/\/cinema.video\/it\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cinema.video\/it\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cinema.video\/it\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre#primaryimage","url":"https:\/\/cinema.video\/wp-content\/uploads\/visioni-3-e1602488248279.jpg","contentUrl":"https:\/\/cinema.video\/wp-content\/uploads\/visioni-3-e1602488248279.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/cinema.video\/it\/visioni-dal-mondo-visioni-incontra-online-dal-17-al-19-settembre#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cinema.video\/it"},{"@type":"ListItem","position":2,"name":"VISIONI DAL MONDO Visioni Incontra Online dal 17 al 19 settembre"}]},{"@type":"WebSite","@id":"https:\/\/cinema.video\/it#website","url":"https:\/\/cinema.video\/it","name":"Cinema & Video International","description":"Film &amp; Audiovisual B2B Industry Trade Platform Magazine","publisher":{"@id":"https:\/\/cinema.video\/it#organization"},"alternateName":"Cinema & Video","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cinema.video\/it?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cinema.video\/it#organization","name":"Cinema & Video","url":"https:\/\/cinema.video\/it","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cinema.video\/it#\/schema\/logo\/image\/","url":"https:\/\/cinema.video\/wp-content\/uploads\/2026\/04\/CinemVideo_LogoBlack.png","contentUrl":"https:\/\/cinema.video\/wp-content\/uploads\/2026\/04\/CinemVideo_LogoBlack.png","width":1336,"height":224,"caption":"Cinema & Video"},"image":{"@id":"https:\/\/cinema.video\/it#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CinemaVideoInternational\/","https:\/\/www.instagram.com\/cinemaevideointernational\/","https:\/\/it.linkedin.com\/company\/cinema-video-international"],"description":"Media Consulting & Marketing Agency","email":"hello@darostudio.com","legalName":"DARO studio LLC","foundingDate":"2021-02-16","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"publishingPrinciples":"https:\/\/cinema.video\/about"},{"@type":"Person","@id":"https:\/\/cinema.video\/it#\/schema\/person\/aeb01b91d874e8b01e76a1db04c668c6","name":"Editorial","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/06ad6f92eb14745b75fb592cadf8139d33242d81c9c8b085133c450aaf0b9731?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/06ad6f92eb14745b75fb592cadf8139d33242d81c9c8b085133c450aaf0b9731?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/06ad6f92eb14745b75fb592cadf8139d33242d81c9c8b085133c450aaf0b9731?s=96&d=mm&r=g","caption":"Editorial"},"url":"https:\/\/cinema.video\/it\/author\/redazione"}]}},"jetpack_shortlink":"https:\/\/wp.me\/ph672m-btU","jetpack_featured_media_url":"https:\/\/cinema.video\/wp-content\/uploads\/visioni-3-e1602488248279.jpg","_links":{"self":[{"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/posts\/44138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/comments?post=44138"}],"version-history":[{"count":2,"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/posts\/44138\/revisions"}],"predecessor-version":[{"id":307922,"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/posts\/44138\/revisions\/307922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/media\/44139"}],"wp:attachment":[{"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/media?parent=44138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/categories?post=44138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinema.video\/it\/wp-json\/wp\/v2\/tags?post=44138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}